{"id":33167,"date":"2023-04-19T13:00:25","date_gmt":"2023-04-19T13:00:25","guid":{"rendered":"https:\/\/actiosoftware.com?p=33167"},"modified":"2026-04-16T15:21:18","modified_gmt":"2026-04-16T18:21:18","slug":"consejos-valiosos-para-retroalimentacion-mas-productiva","status":"publish","type":"post","link":"https:\/\/actiosoftware.com\/es\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/","title":{"rendered":"Valiosos consejos para un feedback m\u00e1s productivo"},"content":{"rendered":"<p>Si recibir feedback ya es una tarea dif\u00edcil para el empleado, \u00bfimagina ser la persona responsable de llevar a cabo todo este proceso?&nbsp;<\/p>\n\n\n\n<p>Tanto si eres jefe de equipo como directivo, es normal que en alg\u00fan momento las personas con las que trabajas cometan errores. Cuando esto ocurre, hay dos opciones: dejarlo pasar y, en consecuencia, provocar que el error se repita, o dar feedback a esa persona.<\/p>\n\n\n\n<p>Est\u00e1 claro que la primera opci\u00f3n parece m\u00e1s f\u00e1cil, pero como el crecimiento de tu equipo est\u00e1 por encima del miedo a dar feedback, sabr\u00e1s que la segunda opci\u00f3n es m\u00e1s adecuada.&nbsp;<\/p>\n\n\n\n<p>Aunque hoy en d\u00eda este tema se trata con m\u00e1s ligereza en la cultura organizativa de las empresas, cuando hablamos de dar feedback sabemos que este momento sigue provocando cierto temor y nerviosismo, tanto en quienes lo reciben como en quienes tienen la misi\u00f3n de darlo.&nbsp;<\/p>\n\n\n\n<p>Aun as\u00ed, podemos indicarte algunos pasos esenciales para ayudarte a tener m\u00e1s confianza a la hora de dar tu opini\u00f3n sobre el trabajo realizado.<\/p>\n\n\n\n<p>Por eso hemos reunido tres consejos importantes para un feedback m\u00e1s productivo que deber\u00edas tener en cuenta a la hora de preparar tu pr\u00f3xima conversaci\u00f3n. Desc\u00fabrelos a continuaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-faca-uma-comunicacao-nao-violenta-nbsp\"><strong>1. Comunicarte de forma no violenta&nbsp;<\/strong><\/h3>\n\n\n\n<p>El primer paso para desarrollar un feedback m\u00e1s productivo es utilizar la comunicaci\u00f3n no violenta (CNV), es decir, entablar un di\u00e1logo con el empleado con empat\u00eda y sin juzgarlo.&nbsp;<\/p>\n\n\n\n<p>El objetivo de este modelo es encontrar la manera de que todos hablen de la necesidad de mejorar, pero sin culpar a la otra persona.  La CNV es muy beneficiosa y se utiliza para resolver conflictos dentro de una organizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Pero recuerda: el feedback no debe darse en presencia de otros compa\u00f1eros de equipo, en reuniones o en cualquier otro entorno que pueda hacer sentir inc\u00f3moda a la persona implicada.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-de-um-feedback-especifico\"><strong>2. Proporciona informaci\u00f3n espec\u00edfica<\/strong><\/h3>\n\n\n\n<p>Es muy importante que, al dar feedback, el otro empleado pueda entender claramente de qu\u00e9 se trata. Al fin y al cabo, un fallo en la comunicaci\u00f3n puede dar lugar a interpretaciones err\u00f3neas o a que el empleado se sienta frustrado dentro de la organizaci\u00f3n, y no queremos que eso ocurra.&nbsp;<\/p>\n\n\n\n<p>Cuando se alaba o elogia el trabajo de alguien de forma gen\u00e9rica, es dif\u00edcil identificar los puntos positivos y negativos del servicio prestado. Por eso es importante ser lo m\u00e1s espec\u00edfico posible.&nbsp;<\/p>\n\n\n\n<p>Por ejemplo, Lais est\u00e1 muy satisfecha con el rendimiento de Tom\u00e1s en el trabajo y quer\u00eda darle un feedback productivo. \u00bfQu\u00e9 opci\u00f3n ser\u00eda m\u00e1s significativa para el desarrollo de Tom\u00e1s?&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Tom\u00e1s, te felicito por tu trabajo. Sigue as\u00ed.<\/li>\n\n\n\n<li>Tom\u00e1s, tu actuaci\u00f3n en la consecuci\u00f3n de los objetivos predefinidos ha sido muy buena y ha generado resultados por encima de la media, \u00a1sigue as\u00ed!<\/li>\n<\/ol>\n\n\n\n<p>Si has elegido la opci\u00f3n n\u00famero 2, vas por buen camino.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-faca-do-feedback-produtivo-uma-pratica-constante\"><strong>3- Haz del feedback productivo una pr\u00e1ctica constante<\/strong><\/h3>\n\n\n\n<p>Las evaluaciones y conversaciones dentro de la empresa deben ser peri\u00f3dicas, para que los empleados empiecen a comprender mejor c\u00f3mo funciona un feedback m\u00e1s productivo. Pero no lo olvides: en todo feedback, los objetivos deben estar bien definidos para que la experiencia forme parte de la rutina diaria de la organizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>La pr\u00e1ctica hace al maestro, as\u00ed que tambi\u00e9n es importante que, para que la experiencia sea cada vez menos inc\u00f3moda, practiques c\u00f3mo dar feedback. Un buen consejo es que te pidas opiniones a ti mismo, as\u00ed aprender\u00e1s a comunicarte mejor y a entender mejor c\u00f3mo perciben tu trabajo los dem\u00e1s.<\/p>\n\n\n\n<p>Para ayudarlo en esta tarea, \u00bfqu\u00e9 tal contar con la ayuda de la tecnolog\u00eda a la hora de dar feedback? Pensando en esto, en asociaci\u00f3n con <a href=\"https:\/\/falconi.com\/\">Falconi<\/a>, desarrollamos <a href=\"https:\/\/actiosoftware.com\/es\/lift-es\/\">Actio Gesti\u00f3n de Desempe\u00f1o<\/a>, un software de gesti\u00f3n de desempe\u00f1o que ayudar\u00e1 en los feedbacks y evaluaciones de desempe\u00f1o en tu empresa.<\/p>\n\n\n\n<p>Te invito a conocerlo: <a href=\"https:\/\/actiosoftware.com\/es\/lift-es\/\">https:\/\/actiosoftware.com\/lift-software-de-gestao-de-desempenho\/<\/a>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>En este blog encontrar\u00e1s tres valiosos consejos para dar un Feedback m\u00e1s productivo, ya seas gerente o colaborador.<\/p>","protected":false},"author":20,"featured_media":33169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[717],"tags":[],"Idioma-posts":[1167],"class_list":["post-33167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-pessoas","idioma-posts-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conselhos valiosos para um Feedback mais produtivo - Actio<\/title>\n<meta name=\"description\" content=\"Neste blog, voc\u00ea vai conferir tr\u00eas conselhos valiosos para dar um Feedback mais produtivo, seja voc\u00ea gestor ou colaborador\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actiosoftware.com\/es\/blog\/consejos-valiosos-para-retroalimentacion-mas-productiva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conselhos valiosos para um Feedback mais produtivo\" \/>\n<meta property=\"og:description\" content=\"Neste blog, voc\u00ea vai conferir tr\u00eas conselhos valiosos para dar um Feedback mais produtivo, seja voc\u00ea gestor ou colaborador\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actiosoftware.com\/es\/blog\/consejos-valiosos-para-retroalimentacion-mas-productiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Actio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/actiobrasil\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T13:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T18:21:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actiosoftware.com\/wp-content\/uploads\/2023\/04\/feedback-positivo-importancia-nas-empresas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heloise Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heloise Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/\"},\"author\":{\"name\":\"Heloise Pontes\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/651267a28d519a2d6599ae4cc4c6f5b0\"},\"headline\":\"Conselhos valiosos para um Feedback mais produtivo\",\"datePublished\":\"2023-04-19T13:00:25+00:00\",\"dateModified\":\"2026-04-16T18:21:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/\"},\"wordCount\":702,\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/feedback-positivo-importancia-nas-empresas.jpg\",\"articleSection\":[\"Gest\u00e3o de Pessoas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/\",\"name\":\"Conselhos valiosos para um Feedback mais produtivo - Actio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/feedback-positivo-importancia-nas-empresas.jpg\",\"datePublished\":\"2023-04-19T13:00:25+00:00\",\"dateModified\":\"2026-04-16T18:21:18+00:00\",\"description\":\"Neste blog, voc\u00ea vai conferir tr\u00eas conselhos valiosos para dar um Feedback mais produtivo, seja voc\u00ea gestor ou colaborador\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/feedback-positivo-importancia-nas-empresas.jpg\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/feedback-positivo-importancia-nas-empresas.jpg\",\"width\":1000,\"height\":677},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/conselhos-valiosos-para-um-feedback-mais-produtivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/actiosoftware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conselhos valiosos para um Feedback mais produtivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"name\":\"Actio\",\"description\":\"Softwares para gest\u00e3o estrat\u00e9gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actiosoftware.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\",\"name\":\"Actio\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"width\":150,\"height\":37,\"caption\":\"Actio\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/actiobrasil\",\"https:\\\/\\\/www.instagram.com\\\/actiobrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/actiosoftware\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/651267a28d519a2d6599ae4cc4c6f5b0\",\"name\":\"Heloise Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g\",\"caption\":\"Heloise Pontes\"},\"description\":\"Product Manager da Actio Software e respons\u00e1vel por conduzir o ciclo de vida dos produtos.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/heloise-pontes\\\/\"],\"url\":\"https:\\\/\\\/actiosoftware.com\\\/es\\\/blog\\\/author\\\/heloise-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Valiosos consejos para un feedback m\u00e1s productivo","description":"En este blog encontrar\u00e1s tres valiosos consejos para dar un Feedback m\u00e1s productivo, ya seas gerente o colaborador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actiosoftware.com\/es\/blog\/consejos-valiosos-para-retroalimentacion-mas-productiva\/","og_locale":"es_ES","og_type":"article","og_title":"Conselhos valiosos para um Feedback mais produtivo","og_description":"Neste blog, voc\u00ea vai conferir tr\u00eas conselhos valiosos para dar um Feedback mais produtivo, seja voc\u00ea gestor ou colaborador","og_url":"https:\/\/actiosoftware.com\/es\/blog\/consejos-valiosos-para-retroalimentacion-mas-productiva\/","og_site_name":"Actio","article_publisher":"https:\/\/www.facebook.com\/actiobrasil","article_published_time":"2023-04-19T13:00:25+00:00","article_modified_time":"2026-04-16T18:21:18+00:00","og_image":[{"width":1000,"height":677,"url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2023\/04\/feedback-positivo-importancia-nas-empresas.jpg","type":"image\/jpeg"}],"author":"Heloise Pontes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Heloise Pontes","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#article","isPartOf":{"@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/"},"author":{"name":"Heloise Pontes","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/651267a28d519a2d6599ae4cc4c6f5b0"},"headline":"Conselhos valiosos para um Feedback mais produtivo","datePublished":"2023-04-19T13:00:25+00:00","dateModified":"2026-04-16T18:21:18+00:00","mainEntityOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/"},"wordCount":702,"publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2023\/04\/feedback-positivo-importancia-nas-empresas.jpg","articleSection":["Gest\u00e3o de Pessoas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/","url":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/","name":"Valiosos consejos para un feedback m\u00e1s productivo","isPartOf":{"@id":"https:\/\/actiosoftware.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#primaryimage"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2023\/04\/feedback-positivo-importancia-nas-empresas.jpg","datePublished":"2023-04-19T13:00:25+00:00","dateModified":"2026-04-16T18:21:18+00:00","description":"En este blog encontrar\u00e1s tres valiosos consejos para dar un Feedback m\u00e1s productivo, ya seas gerente o colaborador.","breadcrumb":{"@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#primaryimage","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2023\/04\/feedback-positivo-importancia-nas-empresas.jpg","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2023\/04\/feedback-positivo-importancia-nas-empresas.jpg","width":1000,"height":677},{"@type":"BreadcrumbList","@id":"https:\/\/actiosoftware.com\/blog\/conselhos-valiosos-para-um-feedback-mais-produtivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/actiosoftware.com\/"},{"@type":"ListItem","position":2,"name":"Conselhos valiosos para um Feedback mais produtivo"}]},{"@type":"WebSite","@id":"https:\/\/actiosoftware.com\/#website","url":"https:\/\/actiosoftware.com\/","name":"Actio","description":"Softwares para gest\u00e3o estrat\u00e9gica","publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actiosoftware.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/actiosoftware.com\/#organization","name":"Actio","url":"https:\/\/actiosoftware.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","width":150,"height":37,"caption":"Actio"},"image":{"@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/actiobrasil","https:\/\/www.instagram.com\/actiobrasil\/","https:\/\/www.linkedin.com\/company\/actiosoftware\/"]},{"@type":"Person","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/651267a28d519a2d6599ae4cc4c6f5b0","name":"Heloise Pontes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g","caption":"Heloise Pontes"},"description":"Gerente de Producto en Actio Software y responsable de dirigir el ciclo de vida de los productos.","sameAs":["https:\/\/www.linkedin.com\/in\/heloise-pontes\/"],"url":"https:\/\/actiosoftware.com\/es\/blog\/author\/heloise-pontes\/"}]}},"_links":{"self":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/33167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/comments?post=33167"}],"version-history":[{"count":2,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/33167\/revisions"}],"predecessor-version":[{"id":68504,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/33167\/revisions\/68504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media\/33169"}],"wp:attachment":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media?parent=33167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/categories?post=33167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/tags?post=33167"},{"taxonomy":"idioma-posts","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/Idioma-posts?post=33167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}