{"id":20233,"date":"2020-03-10T16:54:12","date_gmt":"2020-03-10T16:54:12","guid":{"rendered":"https:\/\/actiosoftware.com?p=20233"},"modified":"2026-04-16T14:59:27","modified_gmt":"2026-04-16T17:59:27","slug":"herramientas-que-transforman-la-gestion-empresarial","status":"publish","type":"post","link":"https:\/\/actiosoftware.com\/es\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/","title":{"rendered":"Inaugurando una nueva etapa en el mercado empresarial, Stratec se convierte en Actio"},"content":{"rendered":"<figure class=\"wp-block-image aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2480\" height=\"1004\" src=\"https:\/\/actiosoftware.comwp-content\/uploads\/2020\/03\/logo-ok.png\" alt=\"Logotipo Actio\" class=\"wp-image-20236\" srcset=\"\" sizes=\"(max-width: 2480px) 100vw, 2480px\" data-srcset=\"\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Hoy, 10 de marzo de 2020, queremos anunciar a nuestros clientes una nueva etapa para nuestra empresa. Este proceso es el resultado de <\/span><span style=\"font-weight: 400;\">a joint venture<\/span><span style=\"font-weight: 400;\"> de Stratec, nuestra antigua identidad, con la <a href=\"https:\/\/falconi.com\/\">Falconi<\/a>, la mayor consultora de gesti\u00f3n de Brasil.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Con m\u00e1s de 15 a\u00f1os en el mercado, hemos crecido significativamente a trav\u00e9s del desarrollo de herramientas de software que ayudan a gestionar grandes empresas. Hoy, damos un paso m\u00e1s hacia el crecimiento optimizando nuestras herramientas con la experiencia de Falconi, en proyectos de gesti\u00f3n implementados en los m\u00e1s variados segmentos del mercado.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Nuestras soluciones est\u00e1n presentes en empresas l\u00edderes de todas las ramas de actividad, incluidos los servicios financieros, el transporte y la log\u00edstica, los bienes de consumo, la alimentaci\u00f3n, la sanidad, la educaci\u00f3n, la tecnolog\u00eda, la energ\u00eda, la miner\u00eda, la metalurgia, la administraci\u00f3n y el sector p\u00fablico, entre otros.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Nuestras acciones se basan en tres pilares fundamentales, con metodolog\u00edas integradas en una \u00fanica plataforma, organizadas en m\u00f3dulos para resolver tus problemas de negocio. Estos pilares son:<\/span><\/p>\n\n\n\n<p><b>Desempe\u00f1o:<\/b><span style=\"font-weight: 400;\"> seguimiento y control del desempe\u00f1o global de la organizaci\u00f3n, desde la ejecuci\u00f3n de la estrategia, el presupuesto, los riesgos, la aplicaci\u00f3n de los objetivos y la gesti\u00f3n de proyectos (Modelo PDCA) hasta la consecuci\u00f3n de los resultados previstos.<\/span><\/p>\n\n\n\n<p><b>Personas:<\/b><span style=\"font-weight: 400;\"> Alineaci\u00f3n basada en las competencias y los intereses de los empleados combinados con las necesidades de la organizaci\u00f3n; centrada en el desempe\u00f1o y el desarrollo de los colaboradores.<\/span><\/p>\n\n\n\n<p><b>Procesos:<\/b><span style=\"font-weight: 400;\"> sistematizaci\u00f3n de las mejores pr\u00e1cticas de gesti\u00f3n de procesos para la estabilizaci\u00f3n y mejora continua de la operaci\u00f3n, persiguiendo el objetivo de la excelencia operativa.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Ahora, tras una trayectoria de constante crecimiento y reconocimiento en el campo de las metodolog\u00edas de gesti\u00f3n empresarial, podemos anunciar con gran satisfacci\u00f3n que somos una empresa del Grupo Falconi. Nuestro compromiso es ofrecer servicios a nuestros clientes basados en los principios de Acci\u00f3n, Desempe\u00f1o y Resultados. Ahora somos Actio.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00ed, tenemos un nuevo nombre, una nueva identidad visual, un nuevo sitio web y una relaci\u00f3n totalmente renovada con nuestros clientes.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Seguiremos avanzando. \u00a1Crezcamos juntos! \u00a1\u00danete al equipo!&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Si quieres resultados, Actio los tiene para ti.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/actiosoftware.comwp-content\/uploads\/2020\/03\/comunicado.gif\" alt=\"\" class=\"wp-image-20234\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span style=\"font-weight: 400;\">Actio,<\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span style=\"font-weight: 400;\">Una empresa del Grupo Falconi.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Durante m\u00e1s de 15 a\u00f1os en el mercado, hemos crecido significativamente desarrollando herramientas digitales que ayudan a gestionar grandes empresas. Hoy, damos un paso m\u00e1s hacia el crecimiento<\/p>","protected":false},"author":20,"featured_media":20238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[717],"tags":[],"Idioma-posts":[1169,1168,1167],"class_list":["post-20233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-pessoas","idioma-posts-espanhol","idioma-posts-ingles","idioma-posts-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferramentas Digitais que Transformam a Gest\u00e3o Empresarial - Actio<\/title>\n<meta name=\"description\" content=\"Com mais de 15 anos de experi\u00eancia, criamos ferramentas digitais para otimizar a gest\u00e3o de grandes empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actiosoftware.com\/es\/blog\/herramientas-que-transforman-la-gestion-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inaugurando uma nova etapa no mercado empresarial, Stratec agora passa a ser Actio\" \/>\n<meta property=\"og:description\" content=\"Com mais de 15 anos de experi\u00eancia, criamos ferramentas digitais para otimizar a gest\u00e3o de grandes empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actiosoftware.com\/es\/blog\/herramientas-que-transforman-la-gestion-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"Actio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/actiobrasil\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T16:54:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T17:59:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/03\/capa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heloise Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heloise Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/\"},\"author\":{\"name\":\"Heloise Pontes\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/651267a28d519a2d6599ae4cc4c6f5b0\"},\"headline\":\"Inaugurando uma nova etapa no mercado empresarial, Stratec agora passa a ser Actio\",\"datePublished\":\"2020-03-10T16:54:12+00:00\",\"dateModified\":\"2026-04-16T17:59:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/\"},\"wordCount\":388,\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/capa-scaled.jpg\",\"articleSection\":[\"Gest\u00e3o de Pessoas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/\",\"name\":\"Ferramentas Digitais que Transformam a Gest\u00e3o Empresarial - Actio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/capa-scaled.jpg\",\"datePublished\":\"2020-03-10T16:54:12+00:00\",\"dateModified\":\"2026-04-16T17:59:27+00:00\",\"description\":\"Com mais de 15 anos de experi\u00eancia, criamos ferramentas digitais para otimizar a gest\u00e3o de grandes empresas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/capa-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/capa-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/actiosoftware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inaugurando uma nova etapa no mercado empresarial, Stratec agora passa a ser Actio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"name\":\"Actio\",\"description\":\"Softwares para gest\u00e3o estrat\u00e9gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actiosoftware.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\",\"name\":\"Actio\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"width\":150,\"height\":37,\"caption\":\"Actio\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/actiobrasil\",\"https:\\\/\\\/www.instagram.com\\\/actiobrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/actiosoftware\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/651267a28d519a2d6599ae4cc4c6f5b0\",\"name\":\"Heloise Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g\",\"caption\":\"Heloise Pontes\"},\"description\":\"Product Manager da Actio Software e respons\u00e1vel por conduzir o ciclo de vida dos produtos.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/heloise-pontes\\\/\"],\"url\":\"https:\\\/\\\/actiosoftware.com\\\/es\\\/blog\\\/author\\\/heloise-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Herramientas que transforman la gesti\u00f3n empresarial","description":"Con m\u00e1s de 15 a\u00f1os de experiencia, creamos herramientas digitales para optimizar la gesti\u00f3n de grandes empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actiosoftware.com\/es\/blog\/herramientas-que-transforman-la-gestion-empresarial\/","og_locale":"es_ES","og_type":"article","og_title":"Inaugurando uma nova etapa no mercado empresarial, Stratec agora passa a ser Actio","og_description":"Com mais de 15 anos de experi\u00eancia, criamos ferramentas digitais para otimizar a gest\u00e3o de grandes empresas.","og_url":"https:\/\/actiosoftware.com\/es\/blog\/herramientas-que-transforman-la-gestion-empresarial\/","og_site_name":"Actio","article_publisher":"https:\/\/www.facebook.com\/actiobrasil","article_published_time":"2020-03-10T16:54:12+00:00","article_modified_time":"2026-04-16T17:59:27+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/03\/capa-scaled.jpg","type":"image\/jpeg"}],"author":"Heloise Pontes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Heloise Pontes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#article","isPartOf":{"@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/"},"author":{"name":"Heloise Pontes","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/651267a28d519a2d6599ae4cc4c6f5b0"},"headline":"Inaugurando uma nova etapa no mercado empresarial, Stratec agora passa a ser Actio","datePublished":"2020-03-10T16:54:12+00:00","dateModified":"2026-04-16T17:59:27+00:00","mainEntityOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/"},"wordCount":388,"publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/03\/capa-scaled.jpg","articleSection":["Gest\u00e3o de Pessoas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/","url":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/","name":"Herramientas que transforman la gesti\u00f3n empresarial","isPartOf":{"@id":"https:\/\/actiosoftware.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#primaryimage"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/03\/capa-scaled.jpg","datePublished":"2020-03-10T16:54:12+00:00","dateModified":"2026-04-16T17:59:27+00:00","description":"Con m\u00e1s de 15 a\u00f1os de experiencia, creamos herramientas digitales para optimizar la gesti\u00f3n de grandes empresas.","breadcrumb":{"@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#primaryimage","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/03\/capa-scaled.jpg","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/03\/capa-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/actiosoftware.com\/blog\/inaugurando-uma-nova-etapa-no-mercado-empresarial-stratec-agora-passa-a-ser-actio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/actiosoftware.com\/"},{"@type":"ListItem","position":2,"name":"Inaugurando uma nova etapa no mercado empresarial, Stratec agora passa a ser Actio"}]},{"@type":"WebSite","@id":"https:\/\/actiosoftware.com\/#website","url":"https:\/\/actiosoftware.com\/","name":"Actio","description":"Softwares para gest\u00e3o estrat\u00e9gica","publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actiosoftware.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/actiosoftware.com\/#organization","name":"Actio","url":"https:\/\/actiosoftware.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","width":150,"height":37,"caption":"Actio"},"image":{"@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/actiobrasil","https:\/\/www.instagram.com\/actiobrasil\/","https:\/\/www.linkedin.com\/company\/actiosoftware\/"]},{"@type":"Person","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/651267a28d519a2d6599ae4cc4c6f5b0","name":"Heloise Pontes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a442dab2b7b38df0f240edb9afe33f93aa79552c397387f92510b56f0ec1a87?s=96&d=mm&r=g","caption":"Heloise Pontes"},"description":"Gerente de Producto en Actio Software y responsable de dirigir el ciclo de vida de los productos.","sameAs":["https:\/\/www.linkedin.com\/in\/heloise-pontes\/"],"url":"https:\/\/actiosoftware.com\/es\/blog\/author\/heloise-pontes\/"}]}},"_links":{"self":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/20233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/comments?post=20233"}],"version-history":[{"count":2,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/20233\/revisions"}],"predecessor-version":[{"id":68471,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/20233\/revisions\/68471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media\/20238"}],"wp:attachment":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media?parent=20233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/categories?post=20233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/tags?post=20233"},{"taxonomy":"idioma-posts","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/Idioma-posts?post=20233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}