{"id":17532,"date":"2013-08-07T13:37:50","date_gmt":"2013-08-07T13:37:50","guid":{"rendered":"http:\/\/novosite.stratec.com.br\/empresa-brasileira-lidera-ranking-de-praticas-de-sustentabilidade\/"},"modified":"2026-02-24T15:08:14","modified_gmt":"2026-02-24T18:08:14","slug":"brasil-liderazgo-sostenibilidad","status":"publish","type":"post","link":"https:\/\/actiosoftware.com\/es\/blog\/lideranca-brasileira-sustentabilidade\/","title":{"rendered":"Empresa brasile\u00f1a lidera ranking de sostenibilidad"},"content":{"rendered":"<p>Brasil es el \u00fanico pa\u00eds de Am\u00e9rica Latina que lidera uno de los 58 sectores investigados para la publicaci\u00f3n del Anuario de Sostenibilidad 2011, seg\u00fan inform\u00f3 el Portal HSM. Seg\u00fan el art\u00edculo, la encuesta establece metodolog\u00edas espec\u00edficas para medir las acciones de sostenibilidad realizadas por las empresas, as\u00ed como su seguimiento y evoluci\u00f3n.<\/p>\n<p>Ita\u00fasa \u2013 Investimentos Ita\u00fa logr\u00f3 liderazgo en el ranking del sector financiero. Tambi\u00e9n seg\u00fan el portal, la empresa viene desarrollando una pol\u00edtica de sostenibilidad desde 2009, con el objetivo de reducir los impactos de sus operaciones en el medio ambiente y la sociedad. Entre las acciones que dieron lugar al ranking se encuentran los programas Green IT y la incorporaci\u00f3n de tecnolog\u00edas ecoeficientes.<\/p>\n<p>Tambi\u00e9n destaca pr\u00e1cticas que facilitan la comunicaci\u00f3n con los clientes. Adem\u00e1s de reforzar la colaboraci\u00f3n con los \u00f3rganos de protecci\u00f3n al consumidor, Ita\u00fasa cre\u00f3, por ejemplo, consejos para el uso consciente del cr\u00e9dito. El presidente del Banco Ita\u00fa, Roberto Setubal, habl\u00f3 sobre la importancia de las iniciativas para la gesti\u00f3n de la empresa, en entrevista con Portal HSM \u201cLa sostenibilidad est\u00e1 en la esencia de nuestro negocio. Y es por eso que buscamos combinar consistentemente el desempe\u00f1o financiero y la competencia gerencial con actitudes que prioricen la \u00e9tica y la transparencia. Este es nuestro diferenciador competitivo y el elemento que nos impulsa a lograr resultados importantes\u201d.<\/p>\n<p>Seg\u00fan informa el portal HSM, el Anuario de Sostenibilidad es elaborado por las consultoras Pricewaterhousecoopers (PwC) y Sustainable Asset Management (SAM). En la edici\u00f3n de 2011, el ranking analiz\u00f3 58 sectores de la econom\u00eda y m\u00e1s de 2.000 empresas, entre las 2.500 mayores del mundo, seg\u00fan el Dow Jones Global Total Stock Market Index.<\/p>","protected":false},"excerpt":{"rendered":"<p>Brasil es el \u00fanico pa\u00eds de Am\u00e9rica Latina que lidera uno de los 58 sectores investigados para la publicaci\u00f3n del Anuario de Sostenibilidad 2011.<\/p>","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[580],"tags":[],"Idioma-posts":[1169,1168,1167],"class_list":["post-17532","post","type-post","status-publish","format-standard","hentry","category-outros","idioma-posts-espanhol","idioma-posts-ingles","idioma-posts-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Empresa brasileira lidera ranking de sustentabilidade - Actio<\/title>\n<meta name=\"description\" content=\"O Brasil \u00e9 o \u00fanico pa\u00eds da Am\u00e9rica Latina a liderar um dos 58 setores pesquisados para a divulga\u00e7\u00e3o do Sustainability Yearbook 2011.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actiosoftware.com\/es\/blog\/brasil-liderazgo-sostenibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresa brasileira lidera ranking de sustentabilidade\" \/>\n<meta property=\"og:description\" content=\"O Brasil \u00e9 o \u00fanico pa\u00eds da Am\u00e9rica Latina a liderar um dos 58 setores pesquisados para a divulga\u00e7\u00e3o do Sustainability Yearbook 2011.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actiosoftware.com\/es\/blog\/brasil-liderazgo-sostenibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Actio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/actiobrasil\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-07T13:37:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T18:08:14+00:00\" \/>\n<meta name=\"author\" content=\"Guilherme Barbassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guilherme Barbassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/\"},\"author\":{\"name\":\"Guilherme Barbassa\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/cf23461d8ee5c5a8df7a56866d4ecf65\"},\"headline\":\"Empresa brasileira lidera ranking de sustentabilidade\",\"datePublished\":\"2013-08-07T13:37:50+00:00\",\"dateModified\":\"2026-02-24T18:08:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/\"},\"wordCount\":295,\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"articleSection\":[\"Outros\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/\",\"name\":\"Empresa brasileira lidera ranking de sustentabilidade - Actio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\"},\"datePublished\":\"2013-08-07T13:37:50+00:00\",\"dateModified\":\"2026-02-24T18:08:14+00:00\",\"description\":\"O Brasil \u00e9 o \u00fanico pa\u00eds da Am\u00e9rica Latina a liderar um dos 58 setores pesquisados para a divulga\u00e7\u00e3o do Sustainability Yearbook 2011.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/lideranca-brasileira-sustentabilidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/actiosoftware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa brasileira lidera ranking de sustentabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"name\":\"Actio\",\"description\":\"Softwares para gest\u00e3o estrat\u00e9gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actiosoftware.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\",\"name\":\"Actio\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"width\":150,\"height\":37,\"caption\":\"Actio\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/actiobrasil\",\"https:\\\/\\\/www.instagram.com\\\/actiobrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/actiosoftware\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/cf23461d8ee5c5a8df7a56866d4ecf65\",\"name\":\"Guilherme Barbassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g\",\"caption\":\"Guilherme Barbassa\"},\"description\":\"Guilherme Barbassa \u00e9 CEO da Actio Software, com mais de 20 anos de experi\u00eancia em gest\u00e3o estrat\u00e9gica e transforma\u00e7\u00e3o empresarial. Atua na integra\u00e7\u00e3o entre estrat\u00e9gia, governan\u00e7a e tecnologia, apoiando a alta lideran\u00e7a na constru\u00e7\u00e3o de sistemas de gest\u00e3o orientados a resultados.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/guilherme-barbassa-247b8932\\\/\"],\"url\":\"https:\\\/\\\/actiosoftware.com\\\/es\\\/blog\\\/author\\\/guiceo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Empresa brasile\u00f1a lidera ranking de sostenibilidad","description":"Brasil es el \u00fanico pa\u00eds de Am\u00e9rica Latina que lidera uno de los 58 sectores investigados para la publicaci\u00f3n del Anuario de Sostenibilidad 2011.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actiosoftware.com\/es\/blog\/brasil-liderazgo-sostenibilidad\/","og_locale":"es_ES","og_type":"article","og_title":"Empresa brasileira lidera ranking de sustentabilidade","og_description":"O Brasil \u00e9 o \u00fanico pa\u00eds da Am\u00e9rica Latina a liderar um dos 58 setores pesquisados para a divulga\u00e7\u00e3o do Sustainability Yearbook 2011.","og_url":"https:\/\/actiosoftware.com\/es\/blog\/brasil-liderazgo-sostenibilidad\/","og_site_name":"Actio","article_publisher":"https:\/\/www.facebook.com\/actiobrasil","article_published_time":"2013-08-07T13:37:50+00:00","article_modified_time":"2026-02-24T18:08:14+00:00","author":"Guilherme Barbassa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guilherme Barbassa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/#article","isPartOf":{"@id":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/"},"author":{"name":"Guilherme Barbassa","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/cf23461d8ee5c5a8df7a56866d4ecf65"},"headline":"Empresa brasileira lidera ranking de sustentabilidade","datePublished":"2013-08-07T13:37:50+00:00","dateModified":"2026-02-24T18:08:14+00:00","mainEntityOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/"},"wordCount":295,"publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"articleSection":["Outros"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/","url":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/","name":"Empresa brasile\u00f1a lidera ranking de sostenibilidad","isPartOf":{"@id":"https:\/\/actiosoftware.com\/#website"},"datePublished":"2013-08-07T13:37:50+00:00","dateModified":"2026-02-24T18:08:14+00:00","description":"Brasil es el \u00fanico pa\u00eds de Am\u00e9rica Latina que lidera uno de los 58 sectores investigados para la publicaci\u00f3n del Anuario de Sostenibilidad 2011.","breadcrumb":{"@id":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/actiosoftware.com\/blog\/lideranca-brasileira-sustentabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/actiosoftware.com\/"},{"@type":"ListItem","position":2,"name":"Empresa brasileira lidera ranking de sustentabilidade"}]},{"@type":"WebSite","@id":"https:\/\/actiosoftware.com\/#website","url":"https:\/\/actiosoftware.com\/","name":"Actio","description":"Softwares para gest\u00e3o estrat\u00e9gica","publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actiosoftware.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/actiosoftware.com\/#organization","name":"Actio","url":"https:\/\/actiosoftware.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","width":150,"height":37,"caption":"Actio"},"image":{"@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/actiobrasil","https:\/\/www.instagram.com\/actiobrasil\/","https:\/\/www.linkedin.com\/company\/actiosoftware\/"]},{"@type":"Person","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/cf23461d8ee5c5a8df7a56866d4ecf65","name":"Guilherme Barbassa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g","caption":"Guilherme Barbassa"},"description":"Guilherme Barbassa es CEO de Actio Software, con m\u00e1s de 20 a\u00f1os de experiencia en gesti\u00f3n estrat\u00e9gica y transformaci\u00f3n empresarial. Act\u00faa en la integraci\u00f3n entre estrategia, gobernanza y tecnolog\u00eda, apoyando la alta direcci\u00f3n en la construcci\u00f3n de sistemas de gesti\u00f3n orientados a resultados.","sameAs":["https:\/\/www.linkedin.com\/in\/guilherme-barbassa-247b8932\/"],"url":"https:\/\/actiosoftware.com\/es\/blog\/author\/guiceo\/"}]}},"_links":{"self":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/comments?post=17532"}],"version-history":[{"count":1,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17532\/revisions"}],"predecessor-version":[{"id":66674,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17532\/revisions\/66674"}],"wp:attachment":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media?parent=17532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/categories?post=17532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/tags?post=17532"},{"taxonomy":"idioma-posts","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/Idioma-posts?post=17532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}