{"id":17394,"date":"2013-08-08T14:38:26","date_gmt":"2013-08-08T14:38:26","guid":{"rendered":"http:\/\/novosite.stratec.com.br\/gestao-de-risco-permite-reduzir-impactos-negativos\/"},"modified":"2026-02-24T15:00:25","modified_gmt":"2026-02-24T18:00:25","slug":"la-gestion-de-riesgos-permite-reducir-los-impactos-negativos","status":"publish","type":"post","link":"https:\/\/actiosoftware.com\/es\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/","title":{"rendered":"La Gesti\u00f3n de Riesgos permite reducir los impactos negativos"},"content":{"rendered":"<p>Una etapa importante de la formulaci\u00f3n estrat\u00e9gica \u2013 proceso que origina la planificaci\u00f3n estrat\u00e9gica corporativa \u2013 es el levantamiento de factores externos a la organizaci\u00f3n que pueden impactar negativamente la gesti\u00f3n. Para el director ejecutivo de Stratec, Guilherme Barbassa, esa preocupaci\u00f3n se expresa en herramientas como el reconocido \u201can\u00e1lisis FODA\u201d; metodolog\u00eda enfocada en la evaluaci\u00f3n de fortalezas, debilidades, oportunidades y amenazas y que sirve para posicionar o verificar la posici\u00f3n estrat\u00e9gica de la organizaci\u00f3n en su ambiente de actuaci\u00f3n. \u201cUno de los puntos fundamentales de esta metodolog\u00eda es justamente el an\u00e1lisis de aspectos del escenario que pueden comprometer la ventaja competitiva de la empresa y necesitan ser observados en el contexto de las decisiones estrat\u00e9gicas\u201d, afirma.<\/p>\n<p>Entre los factores com\u00fanmente asociados a este riesgo, Guilherme Barbassa cita los cambios cambiarios y en las tasas de inter\u00e9s, as\u00ed como alteraciones de regulaci\u00f3n y la entrada de nuevos actores en el mercado. Como tambi\u00e9n destaca el director ejecutivo de Stratec, es justamente buscando facilitar el an\u00e1lisis de estos potenciales elementos de impacto negativo; favoreciendo la toma de decisi\u00f3n por la alta administraci\u00f3n, que la Gesti\u00f3n Estrat\u00e9gica (GE) est\u00e1 disponibilizando a los clientes la funcionalidad de Gesti\u00f3n de Riesgo.<\/p>\n<p>\u201cAunque muchas empresas todav\u00eda no desarrollan el concepto de gesti\u00f3n de riesgos, es perceptible la importancia cada vez mayor de mantener una cultura administrativa en ese sentido. Con la utilizaci\u00f3n de la funcionalidad, nuestros clientes eligen dar seguimiento a aspectos de amenaza y sus posibles impactos sobre las metas planeadas estrat\u00e9gicamente, explica el director ejecutivo de Stratec.<\/p>\n<p>Seg\u00fan Neidson Andrade Silva, del equipo de desarrollo y homologaci\u00f3n de la empresa, adem\u00e1s de permitir este seguimiento que favorece la toma de decisiones, la Gesti\u00f3n de Riesgos agrega otra ventaja importante. La herramienta permite que los factores de amenaza se transformen en indicadores f\u00e1cilmente visualizados de acuerdo con la posible interferencia que representen para proyectos o metas trazadas en la planificaci\u00f3n estrat\u00e9gica. \u201cEsto es posible porque el GE permite configurar una matriz de riesgo, que permite este cruce de datos y agiliza el trabajo del gestor en reducir peligros o replanificar acciones impactadas por elementos externos\u201d, complementa Neidson.<\/p>\n<p>\u201cCon el desarrollo de funcionalidades como la Gesti\u00f3n de Riesgos, Stratec una vez m\u00e1s se adelanta a las necesidades de los clientes y anticipa las demandas actuales del mercado, ofreciendo una soluci\u00f3n que sin duda estar\u00e1 cada vez m\u00e1s presente en la rutina de gesti\u00f3n corporativa. Es una prueba m\u00e1s de nuestra preocupaci\u00f3n por la innovaci\u00f3n y por ofrecer soluciones efectivas\u201d, complementa Guilherme Barbassa, director ejecutivo de Stratec.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una etapa importante en la formulaci\u00f3n estrat\u00e9gica: el proceso que origina la planificaci\u00f3n estrat\u00e9gica corporativa. <\/p>","protected":false},"author":22,"featured_media":17392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[580],"tags":[],"Idioma-posts":[1167],"class_list":["post-17394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outros","idioma-posts-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gest\u00e3o de Riscos permite reduzir impactos negativos - Actio<\/title>\n<meta name=\"description\" content=\"Uma etapa importante da formula\u00e7\u00e3o estrat\u00e9gica \u2013 processo que origina o planejamento estrat\u00e9gico corporativo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actiosoftware.com\/es\/blog\/la-gestion-de-riesgos-permite-reducir-los-impactos-negativos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gest\u00e3o de Riscos permite reduzir impactos negativos\" \/>\n<meta property=\"og:description\" content=\"Uma etapa importante da formula\u00e7\u00e3o estrat\u00e9gica \u2013 processo que origina o planejamento estrat\u00e9gico corporativo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actiosoftware.com\/es\/blog\/la-gestion-de-riesgos-permite-reducir-los-impactos-negativos\/\" \/>\n<meta property=\"og:site_name\" content=\"Actio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/actiobrasil\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-08T14:38:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T18:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actiosoftware.com\/wp-content\/uploads\/2013\/08\/gestaoderisco1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"165\" \/>\n\t<meta property=\"og:image:height\" content=\"94\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fausto Henrique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fausto Henrique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/\"},\"author\":{\"name\":\"Fausto Henrique\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/23c32d60e4c9dc7e5cbe3feaace66d22\"},\"headline\":\"Gest\u00e3o de Riscos permite reduzir impactos negativos\",\"datePublished\":\"2013-08-08T14:38:26+00:00\",\"dateModified\":\"2026-02-24T18:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/\"},\"wordCount\":449,\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/gestaoderisco1.jpg\",\"articleSection\":[\"Outros\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/\",\"name\":\"Gest\u00e3o de Riscos permite reduzir impactos negativos - Actio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/gestaoderisco1.jpg\",\"datePublished\":\"2013-08-08T14:38:26+00:00\",\"dateModified\":\"2026-02-24T18:00:25+00:00\",\"description\":\"Uma etapa importante da formula\u00e7\u00e3o estrat\u00e9gica \u2013 processo que origina o planejamento estrat\u00e9gico corporativo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/gestaoderisco1.jpg\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/gestaoderisco1.jpg\",\"width\":165,\"height\":94},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/gestao-de-risco-permite-reduzir-impactos-negativos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/actiosoftware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gest\u00e3o de Riscos permite reduzir impactos negativos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"name\":\"Actio\",\"description\":\"Softwares para gest\u00e3o estrat\u00e9gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actiosoftware.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\",\"name\":\"Actio\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"width\":150,\"height\":37,\"caption\":\"Actio\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/actiobrasil\",\"https:\\\/\\\/www.instagram.com\\\/actiobrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/actiosoftware\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/23c32d60e4c9dc7e5cbe3feaace66d22\",\"name\":\"Fausto Henrique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84b5e293a7ac339aeee6204b7757d378bf500041fab3ff368a6f8cd4a5b5fe1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84b5e293a7ac339aeee6204b7757d378bf500041fab3ff368a6f8cd4a5b5fe1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84b5e293a7ac339aeee6204b7757d378bf500041fab3ff368a6f8cd4a5b5fe1d?s=96&d=mm&r=g\",\"caption\":\"Fausto Henrique\"},\"description\":\"Product Manager na Actio Software e respons\u00e1vel por alinhar a estrat\u00e9gia de neg\u00f3cio \u00e0s demandas dos clientes, conduzindo a evolu\u00e7\u00e3o cont\u00ednua dos produtos.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fausto-henrique\\\/\"],\"url\":\"https:\\\/\\\/actiosoftware.com\\\/es\\\/blog\\\/author\\\/fausto-henrique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Gesti\u00f3n de Riesgos permite reducir los impactos negativos","description":"Una etapa importante en la formulaci\u00f3n estrat\u00e9gica: el proceso que origina la planificaci\u00f3n estrat\u00e9gica corporativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actiosoftware.com\/es\/blog\/la-gestion-de-riesgos-permite-reducir-los-impactos-negativos\/","og_locale":"es_ES","og_type":"article","og_title":"Gest\u00e3o de Riscos permite reduzir impactos negativos","og_description":"Uma etapa importante da formula\u00e7\u00e3o estrat\u00e9gica \u2013 processo que origina o planejamento estrat\u00e9gico corporativo","og_url":"https:\/\/actiosoftware.com\/es\/blog\/la-gestion-de-riesgos-permite-reducir-los-impactos-negativos\/","og_site_name":"Actio","article_publisher":"https:\/\/www.facebook.com\/actiobrasil","article_published_time":"2013-08-08T14:38:26+00:00","article_modified_time":"2026-02-24T18:00:25+00:00","og_image":[{"width":165,"height":94,"url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2013\/08\/gestaoderisco1.jpg","type":"image\/jpeg"}],"author":"Fausto Henrique","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fausto Henrique","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#article","isPartOf":{"@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/"},"author":{"name":"Fausto Henrique","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/23c32d60e4c9dc7e5cbe3feaace66d22"},"headline":"Gest\u00e3o de Riscos permite reduzir impactos negativos","datePublished":"2013-08-08T14:38:26+00:00","dateModified":"2026-02-24T18:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/"},"wordCount":449,"publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2013\/08\/gestaoderisco1.jpg","articleSection":["Outros"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/","url":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/","name":"La Gesti\u00f3n de Riesgos permite reducir los impactos negativos","isPartOf":{"@id":"https:\/\/actiosoftware.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#primaryimage"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2013\/08\/gestaoderisco1.jpg","datePublished":"2013-08-08T14:38:26+00:00","dateModified":"2026-02-24T18:00:25+00:00","description":"Una etapa importante en la formulaci\u00f3n estrat\u00e9gica: el proceso que origina la planificaci\u00f3n estrat\u00e9gica corporativa.","breadcrumb":{"@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#primaryimage","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2013\/08\/gestaoderisco1.jpg","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2013\/08\/gestaoderisco1.jpg","width":165,"height":94},{"@type":"BreadcrumbList","@id":"https:\/\/actiosoftware.com\/blog\/gestao-de-risco-permite-reduzir-impactos-negativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/actiosoftware.com\/"},{"@type":"ListItem","position":2,"name":"Gest\u00e3o de Riscos permite reduzir impactos negativos"}]},{"@type":"WebSite","@id":"https:\/\/actiosoftware.com\/#website","url":"https:\/\/actiosoftware.com\/","name":"Actio","description":"Softwares para gest\u00e3o estrat\u00e9gica","publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actiosoftware.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/actiosoftware.com\/#organization","name":"Actio","url":"https:\/\/actiosoftware.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","width":150,"height":37,"caption":"Actio"},"image":{"@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/actiobrasil","https:\/\/www.instagram.com\/actiobrasil\/","https:\/\/www.linkedin.com\/company\/actiosoftware\/"]},{"@type":"Person","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/23c32d60e4c9dc7e5cbe3feaace66d22","name":"Fausto Enrique","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/84b5e293a7ac339aeee6204b7757d378bf500041fab3ff368a6f8cd4a5b5fe1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84b5e293a7ac339aeee6204b7757d378bf500041fab3ff368a6f8cd4a5b5fe1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84b5e293a7ac339aeee6204b7757d378bf500041fab3ff368a6f8cd4a5b5fe1d?s=96&d=mm&r=g","caption":"Fausto Henrique"},"description":"Gerente de Producto en Actio Software y responsable de alinear la estrategia de negocio con las demandas de los clientes, impulsando la evoluci\u00f3n continua de los productos.","sameAs":["https:\/\/www.linkedin.com\/in\/fausto-henrique\/"],"url":"https:\/\/actiosoftware.com\/es\/blog\/author\/fausto-henrique\/"}]}},"_links":{"self":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/comments?post=17394"}],"version-history":[{"count":1,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17394\/revisions"}],"predecessor-version":[{"id":66528,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17394\/revisions\/66528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media\/17392"}],"wp:attachment":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media?parent=17394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/categories?post=17394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/tags?post=17394"},{"taxonomy":"idioma-posts","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/Idioma-posts?post=17394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}