{"id":17302,"date":"2014-04-08T17:05:34","date_gmt":"2014-04-08T17:05:34","guid":{"rendered":"http:\/\/novosite.stratec.com.br\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/"},"modified":"2026-02-24T15:08:13","modified_gmt":"2026-02-24T18:08:13","slug":"sistematizar-la-gestion-estrategica-con-la-ausencia-de-tiempo","status":"publish","type":"post","link":"https:\/\/actiosoftware.com\/es\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/","title":{"rendered":"Sistematiza la gesti\u00f3n estrat\u00e9gica en la ausencia de tiempo"},"content":{"rendered":"<h2>Muchos gerentes se enfrentan al reto de la falta de tiempo para sistematizar la gesti\u00f3n de sus organizaciones. \u00bfC\u00f3mo organizarse para invertir en la estrategia?<\/h2>\n<p>El escenario que se presenta actualmente en el mercado revela un panorama lleno de retos a superar por las organizaciones. A partir de la creciente competitividad, la actuaci\u00f3n en forma de redes, el cambio tecnol\u00f3gico y la escasez de recursos, puntos que despiertan la necesidad de invertir en mejoras de procesos y resultados. La gesti\u00f3n de la organizaci\u00f3n alivia a los gerentes y permite que puedan pensar de forma estrat\u00e9gica en la direcci\u00f3n de la empresa, sobre c\u00f3mo superar los retos y, en particular, la forma de evitarlos. \u00bfPero c\u00f3mo conseguir el tiempo para invertir en la gesti\u00f3n estrat\u00e9gica de la empresa?<\/p>\n<p>Seg\u00fan Priscilla Nogueira, Directora de Alianzas Estrat\u00e9gicas en Actio, las empresas que actualmente tienen estructuras ligeras, mucho que hacer en la vida cotidiana. As\u00ed, es com\u00fan escuchar que no hay tiempo para implementar la gesti\u00f3n de la organizaci\u00f3n. La urgente parece siempre superar lo necesario. Para revertir esta situaci\u00f3n tiene una sugerencia \u201cRecomiendo disciplina. Bloquee su horario por lo menos una vez a la semana y comience el proceso de implementaci\u00f3n. Planear, planear, planear y seguir a lo planeado. Planificar y gestionar r\u00e1pidamente permite la identificaci\u00f3n de lo que es realmente importante, y la reducci\u00f3n de los problemas cr\u00f3nicos que requieren energ\u00eda y tiempo en su soluci\u00f3n\u201d, aconseja.<\/p>\n<p>Las organizaciones con modelos estructurados en la gesti\u00f3n empresarial al identificar claramente lo que es y no es importante para el \u00e9xito del negocio en el corto, mediano y largo plazo, pueden coordinar las iniciativas internas, y responden con rapidez y firmeza a las oportunidades y los problemas cotidianos del mercado. Para Priscilla, la coordinaci\u00f3n de los equipos tambi\u00e9n se ve facilitada, ya que la gente puede entender con mayor claridad cu\u00e1l es su contribuci\u00f3n a la empresa, as\u00ed como los auto- ajustes de su atenci\u00f3n en el d\u00eda a d\u00eda.<\/p>\n<p>Seg\u00fan Guilherme Barbassa, Director Ejecutivo de Actio, la realidad de los negocios de hoy persiguen productividad y menos tiempo para planear. \u201cLos directivos est\u00e1n ocupados en la operaci\u00f3n sin pensar acerca de la estrategia. Para la implementaci\u00f3n de una pr\u00e1ctica de gesti\u00f3n requiere un esfuerzo inicial significativo para crear un plan y llevarlo a cabo\u201d, coment\u00f3.<\/p>\n<p>\u201cLa implementaci\u00f3n de un modelo de gesti\u00f3n estrat\u00e9gica debe incluir la planeaci\u00f3n de los objetivos a largo plazo, las metas en su desarrollo, el desarrollo de planes de acci\u00f3n para lograr estas metas y la definici\u00f3n de las pr\u00e1cticas de gesti\u00f3n para su monitoreo\u201d, se\u00f1al\u00f3 Priscila. Ella advierte sobre el hecho de que estas actividades, desarrolladas con la disciplina, se pueden realizar de uno a tres meses, dependiendo de la complejidad y la experiencia de las personas que conducen la implementaci\u00f3n, recordando siempre que los ajustes son naturales a trav\u00e9s del tiempo, con el aumento de los conocimientos acerca de la gesti\u00f3n y la organizaci\u00f3n.<\/p>\n<p>Es importante destacar que, adem\u00e1s de ser un proceso r\u00e1pido de implantar, los resultados pueden verse al instante. \"Los resultados son inmediatos. Si la implementaci\u00f3n se ha realizado correctamente, con la participaci\u00f3n de los equipos, y las pr\u00e1cticas de gesti\u00f3n se est\u00e1n llevando a cabo con disciplina, en el primer mes ser\u00e1 posible identificar una mayor alineaci\u00f3n de los esfuerzos organizativos\", afirma Priscila.  Los resultados financieros pueden ser inmediatos o no, dependiendo de la calidad de los planes de acci\u00f3n elaborados y de su ejecuci\u00f3n. Otro factor a tener en cuenta es el tipo de mercado en el que opera la organizaci\u00f3n. Las organizaciones con ciclos operativos m\u00e1s largos pueden tardar m\u00e1s en ver resultados financieros. \"Pero llegar\u00e1n, seguro\", confirma.<\/p>\n<p>Cabe recordar que toda la gesti\u00f3n estrat\u00e9gica requiere disciplina, informaci\u00f3n y comunicaci\u00f3n para que pueda suceder. El software de Gesti\u00f3n Estrat\u00e9gica ayuda a los administradores en la disciplina, la programaci\u00f3n de reuniones y la advertencia de retrasos sobre acciones y metas que no se cumplen. Proporcionando tambi\u00e9n apoyo a las decisiones de forma r\u00e1pida, visualizaci\u00f3n de informaci\u00f3n pr\u00e1ctica, de metas, indicadores y planes de acci\u00f3n. A su vez, permite que la comunicaci\u00f3n y la visibilidad est\u00e9n garantizadas a trav\u00e9s de las pantallas de gesti\u00f3n a la vista, as\u00ed como al acceso de informaci\u00f3n personalizada a los diferentes niveles de la organizaci\u00f3n. Toda esta pr\u00e1ctica, r\u00e1pida y fiable.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-18587 size-full\" src=\"https:\/\/actiosoftware.comwp-content\/uploads\/2016\/09\/84.jpg\" alt=\"Software de gesti\u00f3n estrat\u00e9gica\" width=\"600\" height=\"150\" srcset=\"\" sizes=\"(max-width: 600px) 100vw, 600px\" data-srcset=\"\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Muchos directivos enfrentan el desaf\u00edo de la falta de tiempo para sistematizar la gesti\u00f3n de sus organizaciones. \u00bfC\u00f3mo puedes organizarte para invertir en gesti\u00f3n estrat\u00e9gica?<\/p>","protected":false},"author":10,"featured_media":17301,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1246],"tags":[],"Idioma-posts":[1169,1167],"class_list":["post-17302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estrategia-e-performance","idioma-posts-espanhol","idioma-posts-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo - Actio<\/title>\n<meta name=\"description\" content=\"Muitos gestores enfrentam o desafio da falta de tempo para sistematizar a gest\u00e3o de suas organiza\u00e7\u00f5es. Como conseguir se organizar para investir na gest\u00e3o estrat\u00e9gica?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actiosoftware.com\/es\/blog\/sistematizar-la-gestion-estrategica-con-la-ausencia-de-tiempo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo\" \/>\n<meta property=\"og:description\" content=\"Muitos gestores enfrentam o desafio da falta de tempo para sistematizar a gest\u00e3o de suas organiza\u00e7\u00f5es. Como conseguir se organizar para investir na gest\u00e3o estrat\u00e9gica?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actiosoftware.com\/es\/blog\/sistematizar-la-gestion-estrategica-con-la-ausencia-de-tiempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Actio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/actiobrasil\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-08T17:05:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T18:08:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actiosoftware.com\/wp-content\/uploads\/2014\/04\/falta-de-tempo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guilherme Barbassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guilherme Barbassa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/\"},\"author\":{\"name\":\"Guilherme Barbassa\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/cf23461d8ee5c5a8df7a56866d4ecf65\"},\"headline\":\"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo\",\"datePublished\":\"2014-04-08T17:05:34+00:00\",\"dateModified\":\"2026-02-24T18:08:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/\"},\"wordCount\":773,\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/falta-de-tempo.jpg\",\"articleSection\":[\"Estrat\u00e9gia e Performance\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/\",\"name\":\"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo - Actio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/falta-de-tempo.jpg\",\"datePublished\":\"2014-04-08T17:05:34+00:00\",\"dateModified\":\"2026-02-24T18:08:13+00:00\",\"description\":\"Muitos gestores enfrentam o desafio da falta de tempo para sistematizar a gest\u00e3o de suas organiza\u00e7\u00f5es. Como conseguir se organizar para investir na gest\u00e3o estrat\u00e9gica?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/falta-de-tempo.jpg\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/falta-de-tempo.jpg\",\"width\":270,\"height\":269,\"caption\":\"desafio da falta de tempo para sistematizar a gest\u00e3o de suas organiza\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/actiosoftware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"name\":\"Actio\",\"description\":\"Softwares para gest\u00e3o estrat\u00e9gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actiosoftware.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\",\"name\":\"Actio\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"width\":150,\"height\":37,\"caption\":\"Actio\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/actiobrasil\",\"https:\\\/\\\/www.instagram.com\\\/actiobrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/actiosoftware\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/person\\\/cf23461d8ee5c5a8df7a56866d4ecf65\",\"name\":\"Guilherme Barbassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g\",\"caption\":\"Guilherme Barbassa\"},\"description\":\"Guilherme Barbassa \u00e9 CEO da Actio Software, com mais de 20 anos de experi\u00eancia em gest\u00e3o estrat\u00e9gica e transforma\u00e7\u00e3o empresarial. Atua na integra\u00e7\u00e3o entre estrat\u00e9gia, governan\u00e7a e tecnologia, apoiando a alta lideran\u00e7a na constru\u00e7\u00e3o de sistemas de gest\u00e3o orientados a resultados.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/guilherme-barbassa-247b8932\\\/\"],\"url\":\"https:\\\/\\\/actiosoftware.com\\\/es\\\/blog\\\/author\\\/guiceo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gestiona la estrategia incluso con poco tiempo - Actio","description":"Muchos directivos enfrentan el desaf\u00edo de la falta de tiempo para sistematizar la gesti\u00f3n de sus organizaciones. \u00bfC\u00f3mo puedes organizarte para invertir en gesti\u00f3n estrat\u00e9gica?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actiosoftware.com\/es\/blog\/sistematizar-la-gestion-estrategica-con-la-ausencia-de-tiempo\/","og_locale":"es_ES","og_type":"article","og_title":"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo","og_description":"Muitos gestores enfrentam o desafio da falta de tempo para sistematizar a gest\u00e3o de suas organiza\u00e7\u00f5es. Como conseguir se organizar para investir na gest\u00e3o estrat\u00e9gica?","og_url":"https:\/\/actiosoftware.com\/es\/blog\/sistematizar-la-gestion-estrategica-con-la-ausencia-de-tiempo\/","og_site_name":"Actio","article_publisher":"https:\/\/www.facebook.com\/actiobrasil","article_published_time":"2014-04-08T17:05:34+00:00","article_modified_time":"2026-02-24T18:08:13+00:00","og_image":[{"width":270,"height":269,"url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2014\/04\/falta-de-tempo.jpg","type":"image\/jpeg"}],"author":"Guilherme Barbassa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guilherme Barbassa","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#article","isPartOf":{"@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/"},"author":{"name":"Guilherme Barbassa","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/cf23461d8ee5c5a8df7a56866d4ecf65"},"headline":"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo","datePublished":"2014-04-08T17:05:34+00:00","dateModified":"2026-02-24T18:08:13+00:00","mainEntityOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/"},"wordCount":773,"publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2014\/04\/falta-de-tempo.jpg","articleSection":["Estrat\u00e9gia e Performance"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/","url":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/","name":"Gestiona la estrategia incluso con poco tiempo - Actio","isPartOf":{"@id":"https:\/\/actiosoftware.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#primaryimage"},"image":{"@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2014\/04\/falta-de-tempo.jpg","datePublished":"2014-04-08T17:05:34+00:00","dateModified":"2026-02-24T18:08:13+00:00","description":"Muchos directivos enfrentan el desaf\u00edo de la falta de tiempo para sistematizar la gesti\u00f3n de sus organizaciones. \u00bfC\u00f3mo puedes organizarte para invertir en gesti\u00f3n estrat\u00e9gica?","breadcrumb":{"@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#primaryimage","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2014\/04\/falta-de-tempo.jpg","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2014\/04\/falta-de-tempo.jpg","width":270,"height":269,"caption":"desafio da falta de tempo para sistematizar a gest\u00e3o de suas organiza\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/actiosoftware.com\/blog\/como-sistematizar-a-gestao-estrategica-na-falta-de-tempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/actiosoftware.com\/"},{"@type":"ListItem","position":2,"name":"Sistematizar a gest\u00e3o estrat\u00e9gica na falta de tempo"}]},{"@type":"WebSite","@id":"https:\/\/actiosoftware.com\/#website","url":"https:\/\/actiosoftware.com\/","name":"Actio","description":"Softwares para gest\u00e3o estrat\u00e9gica","publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actiosoftware.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/actiosoftware.com\/#organization","name":"Actio","url":"https:\/\/actiosoftware.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","width":150,"height":37,"caption":"Actio"},"image":{"@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/actiobrasil","https:\/\/www.instagram.com\/actiobrasil\/","https:\/\/www.linkedin.com\/company\/actiosoftware\/"]},{"@type":"Person","@id":"https:\/\/actiosoftware.com\/#\/schema\/person\/cf23461d8ee5c5a8df7a56866d4ecf65","name":"Guilherme Barbassa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c8a028cc83375c38ab9e78ddd4576e09a165b689ef24a52f1b6c7c474034ae50?s=96&d=mm&r=g","caption":"Guilherme Barbassa"},"description":"Guilherme Barbassa es CEO de Actio Software, con m\u00e1s de 20 a\u00f1os de experiencia en gesti\u00f3n estrat\u00e9gica y transformaci\u00f3n empresarial. Act\u00faa en la integraci\u00f3n entre estrategia, gobernanza y tecnolog\u00eda, apoyando la alta direcci\u00f3n en la construcci\u00f3n de sistemas de gesti\u00f3n orientados a resultados.","sameAs":["https:\/\/www.linkedin.com\/in\/guilherme-barbassa-247b8932\/"],"url":"https:\/\/actiosoftware.com\/es\/blog\/author\/guiceo\/"}]}},"_links":{"self":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/comments?post=17302"}],"version-history":[{"count":1,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17302\/revisions"}],"predecessor-version":[{"id":66656,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/posts\/17302\/revisions\/66656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media\/17301"}],"wp:attachment":[{"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/media?parent=17302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/categories?post=17302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/tags?post=17302"},{"taxonomy":"idioma-posts","embeddable":true,"href":"https:\/\/actiosoftware.com\/es\/wp-json\/wp\/v2\/Idioma-posts?post=17302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}