{"id":717,"count":113,"description":"","link":"https:\/\/actiosoftware.com\/en\/blog\/category\/gestao-de-pessoas\/","name":"People Management","slug":"people-management","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Blogs de gente &amp; gest\u00e3o - Actio<\/title>\n<meta name=\"description\" content=\"Confira dicas sobre feedback, PDI e o poder da gest\u00e3o de desempenho em nossos blogs, e descubra como isso impacta a gente e a gest\u00e3o de pessoas nas empresas\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Gest\u00e3o de Pessoas\" \/>\n<meta property=\"og:description\" content=\"Confira dicas sobre feedback, PDI e o poder da gest\u00e3o de desempenho em nossos blogs, e descubra como isso impacta a gente e a gest\u00e3o de pessoas nas empresas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actiosoftware.com\/en\/blog\/category\/people-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Actio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/category\\\/gestao-de-pessoas\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/category\\\/gestao-de-pessoas\\\/\",\"name\":\"Blogs de gente & gest\u00e3o - Actio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\"},\"description\":\"Confira dicas sobre feedback, PDI e o poder da gest\u00e3o de desempenho em nossos blogs, e descubra como isso impacta a gente e a gest\u00e3o de pessoas nas empresas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/category\\\/gestao-de-pessoas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/blog\\\/category\\\/gestao-de-pessoas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/actiosoftware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gest\u00e3o de Pessoas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#website\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"name\":\"Actio\",\"description\":\"Softwares para gest\u00e3o estrat\u00e9gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actiosoftware.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#organization\",\"name\":\"Actio\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"contentUrl\":\"https:\\\/\\\/actiosoftware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-150x37-3.png\",\"width\":150,\"height\":37,\"caption\":\"Actio\"},\"image\":{\"@id\":\"https:\\\/\\\/actiosoftware.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/actiobrasil\",\"https:\\\/\\\/www.instagram.com\\\/actiobrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/actiosoftware\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blogs de gente & gest\u00e3o - Actio","description":"Check out tips on feedback, PDI and the power of performance management in our blogs, and find out how it impacts us and people management in companies","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Arquivos Gest\u00e3o de Pessoas","og_description":"Confira dicas sobre feedback, PDI e o poder da gest\u00e3o de desempenho em nossos blogs, e descubra como isso impacta a gente e a gest\u00e3o de pessoas nas empresas","og_url":"https:\/\/actiosoftware.com\/en\/blog\/category\/people-management\/","og_site_name":"Actio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/actiosoftware.com\/blog\/category\/gestao-de-pessoas\/","url":"https:\/\/actiosoftware.com\/blog\/category\/gestao-de-pessoas\/","name":"People &amp; management blogs - Actio","isPartOf":{"@id":"https:\/\/actiosoftware.com\/#website"},"description":"Check out tips on feedback, PDI and the power of performance management in our blogs, and find out how it impacts us and people management in companies","breadcrumb":{"@id":"https:\/\/actiosoftware.com\/blog\/category\/gestao-de-pessoas\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/actiosoftware.com\/blog\/category\/gestao-de-pessoas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/actiosoftware.com\/"},{"@type":"ListItem","position":2,"name":"Gest\u00e3o de Pessoas"}]},{"@type":"WebSite","@id":"https:\/\/actiosoftware.com\/#website","url":"https:\/\/actiosoftware.com\/","name":"Actio","description":"Software for strategic management","publisher":{"@id":"https:\/\/actiosoftware.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actiosoftware.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/actiosoftware.com\/#organization","name":"Actio","url":"https:\/\/actiosoftware.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/","url":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","contentUrl":"https:\/\/actiosoftware.com\/wp-content\/uploads\/2020\/02\/logo-150x37-3.png","width":150,"height":37,"caption":"Actio"},"image":{"@id":"https:\/\/actiosoftware.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/actiobrasil","https:\/\/www.instagram.com\/actiobrasil\/","https:\/\/www.linkedin.com\/company\/actiosoftware\/"]}]}},"_links":{"self":[{"href":"https:\/\/actiosoftware.com\/en\/wp-json\/wp\/v2\/categories\/717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actiosoftware.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/actiosoftware.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/actiosoftware.com\/en\/wp-json\/wp\/v2\/posts?categories=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}